{"id":38,"count":2,"description":"","link":"https:\/\/boldlife.be\/nl\/category\/creatie-en-design\/","name":"Creatie en design","slug":"creatie-en-design","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/boldlife.be\/nl\/wp-json\/wp\/v2\/categories\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boldlife.be\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/boldlife.be\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/boldlife.be\/nl\/wp-json\/wp\/v2\/posts?categories=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}